{"id":3113,"date":"2016-05-30T11:03:46","date_gmt":"2016-05-30T17:03:46","guid":{"rendered":"https:\/\/fabiolamenchelli.com\/?post_type=publicaciones&#038;p=3113"},"modified":"2024-05-30T15:03:27","modified_gmt":"2024-05-30T21:03:27","slug":"sidereal-tide","status":"publish","type":"publicaciones","link":"https:\/\/fabiolamenchelli.com\/es\/publicaciones\/sidereal-tide\/","title":{"rendered":"Marea Sideral"},"content":{"rendered":"<script>fsg_json['fsg_post_3113'] = [\n{id: 1079, image: 'https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/11\/FMPX19_expo_casa_wabi_05.jpg', extlink: '', thumb: 'https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/11\/FMPX19_expo_casa_wabi_05-150x150.jpg', permalink: '', layer: '<div class=\"galleria-infolayer\"><div class=\"galleria-layeritem\" style=\"padding-right: 20px;\"><h1>La Curvatura de la Luz, Fabiola Menchelli, Fundacion Casa Wabi, CDMX<\/h1><\/div><div class=\"galleria-layeritem\" style=\"padding-right: 20px;\"><\/div>'}\n];<\/script>\n<p>La materializaci\u00f3n de este libro es consecuencia de un proceso creativo que inici\u00f3 en el mes de mayo de 2015. Las im\u00e1genes que lo componen fueron tomadas dentro del observatorio de concreto en Casa Wabi, en la costa de Oaxaca, donde viv\u00ed 28 d\u00edas como parte de una residencia art\u00edstica.<\/p>\n<p>El d\u00eda que llegu\u00e9, un fen\u00f3meno natural llamado mar de fondo, nos sorprendi\u00f3 mostr\u00e1ndonos el poder absoluto e indomable del agua: la marea cubr\u00eda la alberca y el suelo vibraba con cada ola. Esa misma noche hab\u00eda luna llena, alguien se cay\u00f3 de un caballo y dos amantes se separaron.<\/p>\n<p>Durante mi estancia recorr\u00ed, repas\u00e9, fotografi\u00e9 el observatorio, fascinada por su composici\u00f3n y estructura. Severo, el concreto me llev\u00f3 a buscar alguna forma de moldearlo por medio de im\u00e1genes. Las curvaturas de la luz y los cortes producidos por el espacio me hicieron pensar, de manera inevitable, en el movimiento del mar. Las im\u00e1genes, conectadas una tras otra, crearon un horizonte que se relaciona, a su vez, con las fases lunares. Marcando el calendario, me di cuenta de que el d\u00eda de mi partida coincidir\u00eda, justamente, con la luna llena.<\/p>\n<p>Al volver a casa, decid\u00ed concretar mi reflexi\u00f3n est\u00e9tica en una pieza que se conforma de 13 libros: uno por cada uno de los ciclos lunares que suceden durante un a\u00f1o. Cada libro es un ciclo compuesto por 28 fotograf\u00edas, y cada fotograf\u00eda mide 24 cent\u00edmetros en consonancia con las 24 horas del d\u00eda terrestre, creando as\u00ed un lunario.<\/p>\n<p>La suma de las 364 fotograf\u00edas es un homenaje a la intuici\u00f3n, a la feminidad, a la fertilidad, al agua que nos compone, cualidades que se vinculan ineludiblemente a nuestra intimidad con la luna. Honran, tambi\u00e9n, a la luz que se refleja y se transmuta en la \u00fanica faz que vemos de la Diosa Blanca, as\u00ed como a la fuerza y las ense\u00f1anzas de cada una de sus fases y ciclos.<\/p>\n<figure id=\"attachment_1081\" aria-describedby=\"caption-attachment-1081\" style=\"width: 529px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/11\/FMPX19_expo_casa_wabi_07-e1573793603164.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1081 size-full\" src=\"https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/11\/FMPX19_expo_casa_wabi_07-e1573793603164.jpg\" alt=\"\" width=\"529\" height=\"659\" srcset=\"https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/11\/FMPX19_expo_casa_wabi_07-e1573793603164.jpg 529w, https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/11\/FMPX19_expo_casa_wabi_07-e1573793603164-241x300.jpg 241w\" sizes=\"(max-width: 529px) 100vw, 529px\" \/><\/a><figcaption id=\"caption-attachment-1081\" class=\"wp-caption-text\">Fabiola Menchelli <br \/>Marea Sideral 2015 &#8211; 2016 <br \/>Artist book <br \/>13 accordion bound books, archival pigment print on Bamboo paper <br \/>28 pages each <br \/>Extended 6.28 in x 22 ft each <br \/>Unique edition<\/figcaption><\/figure>\n<figure id=\"attachment_1079\" aria-describedby=\"caption-attachment-1079\" style=\"width: 2000px\" class=\"wp-caption aligncenter\"><a data-postid=\"fsg_post_3113\" data-imgid=\"1079\" href=\"https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/11\/FMPX19_expo_casa_wabi_05.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1079 size-full\" src=\"https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/11\/FMPX19_expo_casa_wabi_05.jpg\" alt=\"\" width=\"2000\" height=\"1335\" srcset=\"https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/11\/FMPX19_expo_casa_wabi_05.jpg 2000w, https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/11\/FMPX19_expo_casa_wabi_05-300x200.jpg 300w, https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/11\/FMPX19_expo_casa_wabi_05-768x513.jpg 768w, https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/11\/FMPX19_expo_casa_wabi_05-1024x684.jpg 1024w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a><figcaption id=\"caption-attachment-1079\" class=\"wp-caption-text\">Fabiola Menchelli <br \/>Marea Sideral 2015 &#8211; 2016 <br \/>Artist book <br \/>13 accordion bound books, archival pigment print on Bamboo paper <br \/>28 pages each <br \/>Extended 6.28 in x 22 ft each <br \/>Unique edition<\/figcaption><\/figure>\n<figure id=\"attachment_1277\" aria-describedby=\"caption-attachment-1277\" style=\"width: 1920px\" class=\"wp-caption alignnone\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1277 size-full\" src=\"https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/12\/2017_menchelli_marea_sideral_013.jpg\" alt=\"\" width=\"1920\" height=\"1281\" srcset=\"https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/12\/2017_menchelli_marea_sideral_013.jpg 1920w, https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/12\/2017_menchelli_marea_sideral_013-300x200.jpg 300w, https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/12\/2017_menchelli_marea_sideral_013-1024x683.jpg 1024w, https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/12\/2017_menchelli_marea_sideral_013-768x512.jpg 768w, https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/12\/2017_menchelli_marea_sideral_013-1536x1025.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><figcaption id=\"caption-attachment-1277\" class=\"wp-caption-text\">Fabiola Menchelli <br \/>Marea Sideral 2015 &#8211; 2016 <br \/>Artist book <br \/>13 accordion bound books, archival pigment print on Bamboo paper <br \/>28 pages each <br \/>Extended 6.28 in x 22 ft each <br \/>Unique edition<\/figcaption><\/figure>\n<div class=\"mceTemp\"><\/div>\n<figure id=\"attachment_1281\" aria-describedby=\"caption-attachment-1281\" style=\"width: 1920px\" class=\"wp-caption alignnone\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1281 size-full\" src=\"https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/12\/2017_menchelli_marea_sideral_024.jpg\" alt=\"\" width=\"1920\" height=\"1299\" srcset=\"https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/12\/2017_menchelli_marea_sideral_024.jpg 1920w, https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/12\/2017_menchelli_marea_sideral_024-300x203.jpg 300w, https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/12\/2017_menchelli_marea_sideral_024-1024x693.jpg 1024w, https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/12\/2017_menchelli_marea_sideral_024-768x520.jpg 768w, https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/12\/2017_menchelli_marea_sideral_024-1536x1039.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><figcaption id=\"caption-attachment-1281\" class=\"wp-caption-text\">Fabiola Menchelli <br \/>Marea Sideral 2015 &#8211; 2016 <br \/>Artist book <br \/>13 accordion bound books, archival pigment print on Bamboo paper <br \/>28 pages each <br \/>Extended 6.28 in x 22 ft each <br \/>Unique edition<\/figcaption><\/figure>\n<figure id=\"attachment_1278\" aria-describedby=\"caption-attachment-1278\" style=\"width: 1920px\" class=\"wp-caption alignnone\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1278 size-full\" src=\"https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/12\/2017_menchelli_marea_sideral_027.jpg\" alt=\"\" width=\"1920\" height=\"1299\" srcset=\"https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/12\/2017_menchelli_marea_sideral_027.jpg 1920w, https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/12\/2017_menchelli_marea_sideral_027-300x203.jpg 300w, https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/12\/2017_menchelli_marea_sideral_027-1024x693.jpg 1024w, https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/12\/2017_menchelli_marea_sideral_027-768x520.jpg 768w, https:\/\/fabiolamenchelli.com\/wp-content\/uploads\/2019\/12\/2017_menchelli_marea_sideral_027-1536x1039.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><figcaption id=\"caption-attachment-1278\" class=\"wp-caption-text\">Fabiola Menchelli <br \/>Marea Sideral 2015 &#8211; 2016 <br \/>Artist book <br \/>13 accordion bound books, archival pigment print on Bamboo paper <br \/>28 pages each <br \/>Extended 6.28 in x 22 ft each <br \/>Unique edition<\/figcaption><\/figure>\n<p>Estoy inmensamente agradecido a Casa Wabi por la invitaci\u00f3n a pasar estas 28 noches en un espacio como ning\u00fan otro, tan hermoso e inspirador. Gracias por darme el tiempo de estar quieto para crear movimiento.<\/p>\n<p>El proceso creativo tard\u00f3 aproximadamente un a\u00f1o en completarse y no hubiera sido posible sin el apoyo de Casa Wabi. Gracias a Bosco Sodi y Tadao Ando por crear este maravilloso espacio. Gracias a Patricia Mart\u00edn. Gracias desde el fondo de mi coraz\u00f3n a Cristina Nava y Alberto R\u00edos de la Rosa. Gracias a Judith, Lalo, Lucero, Lalito, Do\u00f1a Irma, Genaro, Iv\u00e1n, Galia, James, Katia, Huna, Gaby y Yeni, Rebeca y Sean. Gracias a Brett W. Schultz y a Yautepec por su apoyo incondicional. Gracias a Imagen Virtual, Xavier Gaona, Alana Burns, Ernesto Miranda, Leila Tschopp, Laia Rius y Teresa Carter por sus invaluables consejos y su incre\u00edble trabajo. Gracias a mi maravillosa familia y amigos. Finalmente, gracias a Priscilla Vanneuville: no podr\u00eda haberlo hecho sin t\u00ed.<\/p>","protected":false},"excerpt":{"rendered":"<p>2015 &#8211; 2016<\/p>\n","protected":false},"featured_media":3112,"template":"","meta":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/fabiolamenchelli.com\/es\/wp-json\/wp\/v2\/publicaciones\/3113"}],"collection":[{"href":"https:\/\/fabiolamenchelli.com\/es\/wp-json\/wp\/v2\/publicaciones"}],"about":[{"href":"https:\/\/fabiolamenchelli.com\/es\/wp-json\/wp\/v2\/types\/publicaciones"}],"version-history":[{"count":2,"href":"https:\/\/fabiolamenchelli.com\/es\/wp-json\/wp\/v2\/publicaciones\/3113\/revisions"}],"predecessor-version":[{"id":3117,"href":"https:\/\/fabiolamenchelli.com\/es\/wp-json\/wp\/v2\/publicaciones\/3113\/revisions\/3117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fabiolamenchelli.com\/es\/wp-json\/wp\/v2\/media\/3112"}],"wp:attachment":[{"href":"https:\/\/fabiolamenchelli.com\/es\/wp-json\/wp\/v2\/media?parent=3113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}